{"id":10562,"date":"2018-07-24T22:09:02","date_gmt":"2018-07-24T21:09:02","guid":{"rendered":"https:\/\/canaryo.net\/portal\/?p=10562"},"modified":"2018-07-24T22:09:02","modified_gmt":"2018-07-24T21:09:02","slug":"drogenhandlerring-auf-den-kanaren-zerschlagen-56-festnahmen","status":"publish","type":"post","link":"https:\/\/canaryo.net\/portal\/drogenhandlerring-auf-den-kanaren-zerschlagen-56-festnahmen\/","title":{"rendered":"Drogenh\u00e4ndlerring auf den Kanaren zerschlagen &#8211; 56 Festnahmen"},"content":{"rendered":"<p>Teneriffa\/Gran Canaria; 24.07.2018 &#8211; &#8211; Den Beh\u00f6rden ist es gelungen ein riesiges Drogennetzwerk zu zerschlagen. Die Zollfahndung hat in Zusammenarbeit mit der Policia Nacional und der British National Crime Agency (NCA) eine der bisher gr\u00f6\u00dften kriminellen Organisationen auf den Kanaren entdeckt und ausgehoben. Dabei wurden 56 Personen verschiedener Nationalit\u00e4ten verhaftet. Die Fahnder beschlagnahmten 1,14 Millionen Euro Bargeld, 32 Luxus-Fahrzeuge, f\u00fcnf Yachten sowie Bankkonten und Waren im Wert von 3,97 Millionen Euro. Bei den Durchsuchungen fanden die Beamten 600 Kg Kokain und 2,8 Tonnen Haschisch.<br \/>\nAuf die Spur kamen die Ermittler der Organisation im Mai 2016. Sie stellten fest das Drogen von Gran Canaria nach Teneriffa geschmuggelt wurden und entdeckten eine komplette kriminelle Organisation auf den kanarischen Inseln die gut strukturiert war, die Drogen importierte und weiterverteilte. Unter der Leitung des Gerichts Nr. 3 in La Laguna und dem Sonderstaatsanwalts zur Verh\u00fctung und Bek\u00e4mpfung des illegalen Drogenhandels in Santa Cruz de Tenerife, wurde unter erheblichen personellen und materiellen Einsatzes ermittelt. Die Fahnder entdeckten dass die pyramidenartigen Strukturen in La Isleta und der Innenstadt von Las Palmas de Gran Canaria zusammenlaufen.<br \/>\nDer Import der Drogen erfolgte entweder per Schiffscontainer aus S\u00fcdamerika oder per Fischerboote die ihre Fracht von anderen Booten auf offener See \u00fcbernahmen. Die Container enthielten Fracht von legalen Firmen, welche von der Zweckentfremdung jedoch nichts wussten oder mitbekommen haben. So wurde die Ware heimlich in S\u00fcdamerika in Container versteckt die in Las Palmas umgeladen und weiterverschifft werden sollten. Im Transitbereich in Las Palmas, wurden die Container von angeworbenen Hafenmitarbeitern ge\u00f6ffnet, die Drogen entnommen und die Container anschlie\u00dfend wieder versiegelt, so dass niemand mitbekam was sonst noch in dem Container zwischendurch transportiert wurde. Mehrere dieser Container konnten abgefangen und 600 Kg Kokain sichergestellt werden.<br \/>\nBei der Fischerboot-Variante entluden Segelboote hunderte Km entfernt von der K\u00fcste ihre illegale Fracht aus S\u00fcdamerika auf die Fischerboote. Diese kamen dann offiziell von ihren Fanggebieten zur\u00fcck und entluden ihre Fracht im Fischereihafen. In verschiedenen Operationen wurden in den letzten zwei Jahren 15 Personen festgenommen,vier Boote beschlagnahmt und 2.722 Kg Haschisch sichergestellt.<br \/>\nDie Einnahmen aus dem Drogenverkauf wurden \u00fcber Import-Export-Firmen auf Gran Canaria gewaschen. Diese waren offiziell zum Teil auf den Fischhandel und den Handel von Premium-Fahrzeuge spezialisiert. Die Firmen wurden mehrere Jahre lang betrieben und die dahinter stehende kriminelle Organisation hatte sehr gute Sicherheitsma\u00dfnahmen um nicht aufzufliegen. Dennoch haben die Ermittler es geschafft sie aufzudecken und 56 Mitglieder zu verhaften.<br \/>\nBei 25 Hausdurchsuchungen gab es, neben den bereits erw\u00e4hnten Funden, auch noch weitere Funde, wie eine scharfe Waffe, mehrere Schreckschuss- oder Anscheinswaffen, sowie eine gro\u00dfe Menge an Mobiltelefonen, Computer, Speichermedien, etc., die als Zufallsfunde und Beweismittel sichergestellt wurden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Teneriffa\/Gran Canaria; 24.07.2018 &#8211; &#8211; Den Beh\u00f6rden ist es gelungen ein riesiges Drogennetzwerk zu zerschlagen. Die Zollfahndung hat in Zusammenarbeit mit der Policia Nacional und der British National Crime Agency (NCA) eine der bisher gr\u00f6\u00dften kriminellen Organisationen auf den Kanaren entdeckt und ausgehoben. Dabei wurden 56 Personen verschiedener Nationalit\u00e4ten verhaftet. Die Fahnder beschlagnahmten 1,14 Millionen [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":10563,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":[],"categories":[440,494,6,441],"tags":[1396,524,3833,591,1166,2028,8,590,476,1121,795,435,2861,3671,3835,3836,3834],"_links":{"self":[{"href":"https:\/\/canaryo.net\/portal\/wp-json\/wp\/v2\/posts\/10562"}],"collection":[{"href":"https:\/\/canaryo.net\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canaryo.net\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canaryo.net\/portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/canaryo.net\/portal\/wp-json\/wp\/v2\/comments?post=10562"}],"version-history":[{"count":1,"href":"https:\/\/canaryo.net\/portal\/wp-json\/wp\/v2\/posts\/10562\/revisions"}],"predecessor-version":[{"id":10564,"href":"https:\/\/canaryo.net\/portal\/wp-json\/wp\/v2\/posts\/10562\/revisions\/10564"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canaryo.net\/portal\/wp-json\/wp\/v2\/media\/10563"}],"wp:attachment":[{"href":"https:\/\/canaryo.net\/portal\/wp-json\/wp\/v2\/media?parent=10562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canaryo.net\/portal\/wp-json\/wp\/v2\/categories?post=10562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canaryo.net\/portal\/wp-json\/wp\/v2\/tags?post=10562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}